{"id":3263,"date":"2026-02-03T15:06:17","date_gmt":"2026-02-03T14:06:17","guid":{"rendered":"https:\/\/www.bbqpartseurope.eu\/product\/weber-69413-69898-crossover-burner-tube-spirit-300-series\/"},"modified":"2026-02-03T15:06:17","modified_gmt":"2026-02-03T14:06:17","slug":"weber-69413-69898-crossover-burner-tube-spirit-300-series","status":"publish","type":"product","link":"https:\/\/www.bbqpartseurope.eu\/en\/product\/weber-69413-69898-crossover-burner-tube-spirit-300-series\/","title":{"rendered":"Weber 69413 \/ 69898 Crossover Burner tube Spirit 300 series"},"content":{"rendered":"<p>Weber 69413 \/ 69898 Crossover Burner tube Spirit 300 series.<\/p>\n<p>Voor al je barbecue onderdelen ga je naar BBQParts Europe. De barbecuespecialist van Europa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nummer 5 op het schema.<\/p>\n","protected":false},"featured_media":3264,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[40,60,207],"product_tag":[],"class_list":{"0":"post-3263","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-gas-barbecues","7":"product_cat-spirit","8":"product_cat-spirit-300-2021","9":"product_shipping_class-pakketpost-31-kg","11":"first","12":"onbackorder","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Weber 69413 \/ 69898 Crossover Burner tube Spirit 300 series &#8211; BBQPARTS EUROPE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bbqpartseurope.eu\/en\/product\/weber-69413-69898-crossover-burner-tube-spirit-300-series\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Weber 69413 \/ 69898 Crossover Burner tube Spirit 300 series &#8211; BBQPARTS EUROPE\" \/>\n<meta property=\"og:description\" content=\"Nummer 5 op het schema.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bbqpartseurope.eu\/en\/product\/weber-69413-69898-crossover-burner-tube-spirit-300-series\/\" \/>\n<meta property=\"og:site_name\" content=\"BBQPARTS EUROPE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bbqpartseurope.eu\/en\/product\/weber-69413-69898-crossover-burner-tube-spirit-300-series\/\",\"url\":\"https:\/\/www.bbqpartseurope.eu\/en\/product\/weber-69413-69898-crossover-burner-tube-spirit-300-series\/\",\"name\":\"Weber 69413 \/ 69898 Crossover Burner tube Spirit 300 series &#8211; BBQPARTS EUROPE\",\"isPartOf\":{\"@id\":\"https:\/\/www.bbqpartseurope.eu\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.bbqpartseurope.eu\/en\/product\/weber-69413-69898-crossover-burner-tube-spirit-300-series\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.bbqpartseurope.eu\/en\/product\/weber-69413-69898-crossover-burner-tube-spirit-300-series\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.bbqpartseurope.eu\/wp-content\/uploads\/2026\/02\/Weber-69413-1.jpg\",\"datePublished\":\"2026-02-03T14:06:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.bbqpartseurope.eu\/en\/product\/weber-69413-69898-crossover-burner-tube-spirit-300-series\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bbqpartseurope.eu\/en\/product\/weber-69413-69898-crossover-burner-tube-spirit-300-series\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.bbqpartseurope.eu\/en\/product\/weber-69413-69898-crossover-burner-tube-spirit-300-series\/#primaryimage\",\"url\":\"https:\/\/www.bbqpartseurope.eu\/wp-content\/uploads\/2026\/02\/Weber-69413-1.jpg\",\"contentUrl\":\"https:\/\/www.bbqpartseurope.eu\/wp-content\/uploads\/2026\/02\/Weber-69413-1.jpg\",\"width\":700,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bbqpartseurope.eu\/en\/product\/weber-69413-69898-crossover-burner-tube-spirit-300-series\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.bbqpartseurope.eu\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alle parts\",\"item\":\"https:\/\/www.bbqpartseurope.eu\/en\/all\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Weber 69413 \/ 69898 Crossover Burner tube Spirit 300 series\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bbqpartseurope.eu\/en\/#website\",\"url\":\"https:\/\/www.bbqpartseurope.eu\/en\/\",\"name\":\"BBQPARTS EUROPE\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bbqpartseurope.eu\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Weber 69413 \/ 69898 Crossover Burner tube Spirit 300 series &#8211; BBQPARTS EUROPE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bbqpartseurope.eu\/en\/product\/weber-69413-69898-crossover-burner-tube-spirit-300-series\/","og_locale":"en_US","og_type":"article","og_title":"Weber 69413 \/ 69898 Crossover Burner tube Spirit 300 series &#8211; BBQPARTS EUROPE","og_description":"Nummer 5 op het schema.","og_url":"https:\/\/www.bbqpartseurope.eu\/en\/product\/weber-69413-69898-crossover-burner-tube-spirit-300-series\/","og_site_name":"BBQPARTS EUROPE","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bbqpartseurope.eu\/en\/product\/weber-69413-69898-crossover-burner-tube-spirit-300-series\/","url":"https:\/\/www.bbqpartseurope.eu\/en\/product\/weber-69413-69898-crossover-burner-tube-spirit-300-series\/","name":"Weber 69413 \/ 69898 Crossover Burner tube Spirit 300 series &#8211; BBQPARTS EUROPE","isPartOf":{"@id":"https:\/\/www.bbqpartseurope.eu\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bbqpartseurope.eu\/en\/product\/weber-69413-69898-crossover-burner-tube-spirit-300-series\/#primaryimage"},"image":{"@id":"https:\/\/www.bbqpartseurope.eu\/en\/product\/weber-69413-69898-crossover-burner-tube-spirit-300-series\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bbqpartseurope.eu\/wp-content\/uploads\/2026\/02\/Weber-69413-1.jpg","datePublished":"2026-02-03T14:06:17+00:00","breadcrumb":{"@id":"https:\/\/www.bbqpartseurope.eu\/en\/product\/weber-69413-69898-crossover-burner-tube-spirit-300-series\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bbqpartseurope.eu\/en\/product\/weber-69413-69898-crossover-burner-tube-spirit-300-series\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.bbqpartseurope.eu\/en\/product\/weber-69413-69898-crossover-burner-tube-spirit-300-series\/#primaryimage","url":"https:\/\/www.bbqpartseurope.eu\/wp-content\/uploads\/2026\/02\/Weber-69413-1.jpg","contentUrl":"https:\/\/www.bbqpartseurope.eu\/wp-content\/uploads\/2026\/02\/Weber-69413-1.jpg","width":700,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/www.bbqpartseurope.eu\/en\/product\/weber-69413-69898-crossover-burner-tube-spirit-300-series\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bbqpartseurope.eu\/en\/"},{"@type":"ListItem","position":2,"name":"Alle parts","item":"https:\/\/www.bbqpartseurope.eu\/en\/all\/"},{"@type":"ListItem","position":3,"name":"Weber 69413 \/ 69898 Crossover Burner tube Spirit 300 series"}]},{"@type":"WebSite","@id":"https:\/\/www.bbqpartseurope.eu\/en\/#website","url":"https:\/\/www.bbqpartseurope.eu\/en\/","name":"BBQPARTS EUROPE","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bbqpartseurope.eu\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.bbqpartseurope.eu\/en\/wp-json\/wp\/v2\/product\/3263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bbqpartseurope.eu\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.bbqpartseurope.eu\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bbqpartseurope.eu\/en\/wp-json\/wp\/v2\/media\/3264"}],"wp:attachment":[{"href":"https:\/\/www.bbqpartseurope.eu\/en\/wp-json\/wp\/v2\/media?parent=3263"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.bbqpartseurope.eu\/en\/wp-json\/wp\/v2\/product_brand?post=3263"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.bbqpartseurope.eu\/en\/wp-json\/wp\/v2\/product_cat?post=3263"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.bbqpartseurope.eu\/en\/wp-json\/wp\/v2\/product_tag?post=3263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}